{"id":10162,"date":"2017-11-30T14:29:12","date_gmt":"2017-11-30T14:29:12","guid":{"rendered":"https:\/\/a60047bb09.nxcli.io\/?p=10162"},"modified":"2017-11-30T14:29:12","modified_gmt":"2017-11-30T14:29:12","slug":"los-tuiteros-de-elcomercioencade-analizan-el-segundo-dia","status":"publish","type":"post","link":"https:\/\/inestemple.com\/en\/2017\/11\/los-tuiteros-de-elcomercioencade-analizan-el-segundo-dia\/","title":{"rendered":"Los &#8216;tuiteros&#8217; de #ElComercioenCADE analizan el segundo d\u00eda"},"content":{"rendered":"<hr \/>\n<div id=\"fullwidth\" class=\"full-width\">\n<div class=\"sf elemento generico\">\n<p id=\"p478140-m317-1-318\" class=\"news-title\">Publicado el 30\/11\/2017 en El Comercio<\/p>\n<p id=\"p478140-m327-2-328\" class=\"news-summary\">El gerente general del Instituto Peruano de Econom\u00eda, Diego Macera, y la presidenta de LHH DBM, In\u00e9s Temple, repasan las lecciones aprendidas del segundo d\u00eda de\u00a0<b><a title=\"CADE 2017\" href=\"https:\/\/elcomercio.pe\/noticias\/cade-2017\" target=\"_blank\" rel=\"noopener noreferrer\">CADE 2017<\/a><\/b><\/p>\n<\/div>\n<div class=\"nota elemento \">\n<div class=\"article-media news-media \">\n<div id=\"p478140-m275-274-276\" class=\"main-video video-module media-in-body captioned-image video-content\">\n<div class=\"video-playerss inline\">\n<div class=\"video-module-image\">\n<div id=\"m279-278-280\" class=\"video-player inline video-image image\">\n<div id=\"strobemediaplayback\"><iframe loading=\"lazy\" src=\"https:\/\/elcomercio.pe\/media\/FibzNqZDE66-MtomE8jioIrmQo0S1ZFk?category=Cade&amp;movil=false&amp;autoplay=0\" width=\"620px\" height=\"390\" allowfullscreen=\"allowfullscreen\" data-ads=\"?category=Cade&amp;movil=false\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div class=\"video-module-details\">\n<p id=\"m296-1-297\" class=\"video-description description dd\">Resumen del segundo d\u00eda del CADE 2017 de la mano del IPE y LHH DBM.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"news-column\">\n<div class=\"news-body clearfix\">\n<div class=\"article-content\">\n<div class=\"news-text\">\n<div id=\"contenedor\" class=\"news-text-content \">\n<p id=\"p478140-m312-311-313\" class=\"parrafo first-parrafo\"><b><a title=\"CADE 2017\" href=\"https:\/\/elcomercio.pe\/cade\/elcomercio.pe\/cade\" target=\"_blank\" rel=\"noopener noreferrer\">CADE 2017<\/a><\/b>\u00a0va llegando al final de su segundo d\u00eda y con esto las lecciones y consensos a los que los empresarios van llegando son cada vez m\u00e1s.\u00a0<b>El Comercio<\/b>\u00a0convers\u00f3 con el gerente general del\u00a0<b><a title=\"IPE\" href=\"https:\/\/elcomercio.pe\/cade\/elcomercio.pe\/noticias\/ipe\" target=\"_blank\" rel=\"noopener noreferrer\">Instituto Peruano de Econom\u00eda<\/a><\/b>,\u00a0<b><a title=\"Diego Macera\" href=\"https:\/\/elcomercio.pe\/cade\/elcomercio.pe\/autor\/diego-macera\" target=\"_blank\" rel=\"noopener noreferrer\">Diego Macera<\/a><\/b>, y la presidenta de\u00a0<b><a title=\"LHH DBM\" href=\"https:\/\/elcomercio.pe\/cade\/elcomercio.pe\/noticias\/lhh-dbm-peru\" target=\"_blank\" rel=\"noopener noreferrer\">LHH DBM<\/a><\/b>,\u00a0<b><a title=\"In\u00e9s Temple\" href=\"https:\/\/elcomercio.pe\/cade\/elcomercio.pe\/noticias\/ines-temple\" target=\"_blank\" rel=\"noopener noreferrer\">In\u00e9s Temple<\/a><\/b>, sobre los principales puntos a resaltar de las \u00faltimas 24 horas.<\/p>\n<div id=\"p478140-m322-1-323\" class=\"html_libre\"><\/div>\n<p id=\"p478140-m332-2-333\" class=\"parrafo first-parrafo\">&#8220;Estamos rompiendo la monoton\u00eda de conversar sobre si crecemos 2,8% en el PBI o si se abre o cierra una mina y hemos empezado a pensar en un plazo m\u00e1s largo, lo cual se relaciona con los retos institucionales que enfrentamos: reformas que nos deber\u00edan dar competitividad en los siguientes 15 a\u00f1os&#8221;, detall\u00f3 Macera.<\/p>\n<p id=\"p478140-m337-3-338\" class=\"parrafo first-parrafo\">Por su lado, Temple coment\u00f3 que los problemas del pa\u00eds son varios, pero est\u00e1n bien detallados. En este sentido, afirm\u00f3 que el pa\u00eds necesita mayor integraci\u00f3n de toda la poblaci\u00f3n, especialmente del lado de aquellas personas que no tienen mayores oportunidades de participar en la econom\u00eda nacional.<\/p>\n<p id=\"p478140-m342-4-343\" class=\"parrafo first-parrafo\">&#8220;Necesitamos empezar a utilizar la tecnolog\u00eda para poder mejorar nuestra productividad e integrar a los pobladores m\u00e1s alejados. Pero adem\u00e1s, la educaci\u00f3n sigue siendo el tema de fondo del pa\u00eds. Vemos problemas en cada rubro de la sociedad y estamos viendo resultados desalentadores en cada estudio que analizamos&#8221;, afirm\u00f3 Temple.<\/p>\n<p class=\"parrafo first-parrafo\">Ver en:\u00a0\u00a0<a href=\"https:\/\/elcomercio.pe\/cade\/cade-2017-ipe-lhh-dbm-analizan-segundo-dia-evento-noticia-478140\" target=\"_blank\" rel=\"noopener noreferrer\">www.elcomercio.pe<\/a><\/p>\n<p class=\"parrafo first-parrafo\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/elcomercio.pe\/cade\/cade-2017-ipe-lhh-dbm-analizan-segundo-dia-evento-noticia-478140\" target=\"_blank\" rel=\"noopener noreferrer\"> www.miquiosco.com<\/a><\/p>\n<p class=\"parrafo first-parrafo\">Noticias relacionadas:<\/p>\n<p class=\"parrafo first-parrafo\"><a href=\"https:\/\/elcomercio.pe\/cade\/cade-2017-segunda-jornada-tuiteros-noticia-478173\" target=\"_blank\" rel=\"noopener noreferrer\">CADE 2017: La segunda jornada de los &#8216;tuiteros&#8217; (ver en web)<\/a><\/p>\n<p class=\"parrafo first-parrafo\">\n<p class=\"parrafo first-parrafo\">\n<p class=\"parrafo first-parrafo\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Publicado el 30\/11\/2017 en El Comercio El gerente general del Instituto Peruano de Econom\u00eda, Diego Macera, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":10163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,3],"tags":[5,14,96],"media":[],"class_list":["post-10162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-menciones","tag-administracion-de-carrera","tag-empleabilidad-en","tag-ines-temple"],"acf":[],"_links":{"self":[{"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/posts\/10162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/comments?post=10162"}],"version-history":[{"count":0,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/posts\/10162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/media\/10163"}],"wp:attachment":[{"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/media?parent=10162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/categories?post=10162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/tags?post=10162"},{"taxonomy":"media","embeddable":true,"href":"https:\/\/inestemple.com\/en\/wp-json\/wp\/v2\/media?post=10162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}